{"id":3779,"date":"2025-11-07T18:03:15","date_gmt":"2025-11-07T21:03:15","guid":{"rendered":"https:\/\/dechilealpaladar.cl\/"},"modified":"2025-11-07T20:27:16","modified_gmt":"2025-11-07T23:27:16","slug":"nubles-country-vines-shone-at-taster-2025","status":"publish","type":"post","link":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/","title":{"rendered":"\u00d1uble's small-scale vineyards shone at Catad'Or 2025"},"content":{"rendered":"<p>The Itata Valley's peasant family agriculture once again took centre stage on the international wine scene.<\/p>\n<p>In the 2025 version of the <strong>Catad'Or World Wine Awards<\/strong>The wine Do\u00f1a Elita Cinsault 2022, produced by Elia Fierro's Do\u00f1a Elita winery in the commune of R\u00e1nquil, won a Grand Gold Medal and the Trophy for Best Ancestral Wine, consolidating its trajectory as one of the country's most renowned producers in the rescue of heritage grape varieties.<\/p>\n<p>The recognition adds to a historic performance for \u00d1uble: 10 other family wineries in the region won 14 gold medals, highlighting the talent, innovation and territorial roots of small producers supported by INDAP in the Itata Valley.<\/p>\n<p>Award-winning vineyards include <strong>Trifulca, Cortez, El Guindo, Guarilihue Familiar, Hermanos D\u00edaz, La Kura, La Misi\u00f3n de Francisco, San Luis, Tres C, and Viejo Encino.<\/strong>with labels that reflect the diversity and unique character of the territory. Each one of them represents the efforts of families who, with dedication and collective work, have turned the Itata winemaking tradition into a benchmark of regional and national identity.<\/p>\n<figure id=\"attachment_3783\" aria-describedby=\"caption-attachment-3783\" style=\"width: 406px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-3783\" src=\"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/gran-oro-vino-ancestral_catador-2025.jpg\" alt=\"\" width=\"406\" height=\"317\" srcset=\"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/gran-oro-vino-ancestral_catador-2025.jpg 1547w, https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/gran-oro-vino-ancestral_catador-2025-300x234.jpg 300w, https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/gran-oro-vino-ancestral_catador-2025-1024x799.jpg 1024w, https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/gran-oro-vino-ancestral_catador-2025-768x599.jpg 768w, https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/gran-oro-vino-ancestral_catador-2025-1536x1198.jpg 1536w, https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/gran-oro-vino-ancestral_catador-2025-15x12.jpg 15w, https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/gran-oro-vino-ancestral_catador-2025-750x585.jpg 750w, https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/gran-oro-vino-ancestral_catador-2025-1140x889.jpg 1140w\" sizes=\"(max-width: 406px) 100vw, 406px\" \/><figcaption id=\"caption-attachment-3783\" class=\"wp-caption-text\">Elia Fierro, producer of Vi\u00f1a Do\u00f1a Elita, winner of Grand Gold and Best Ancestral Wine at Catad'Or 2025<\/figcaption><\/figure>\n<p>For Elia Fierro, producer of Vi\u00f1a Do\u00f1a Elita, this award \"rewards all the effort and work that goes into each bottle. In the vineyard we work all year round, without rest. This award is of immense value to me, because I make the wine myself, I review it every day and then I consult an oenologist just to adjust the details\".<\/p>\n<p>INDAP \u00d1uble highlighted that these results confirm the sustained growth of the valley around the peasant viticulture, driven by associative programmes, technical advice and commercial promotion that strengthen the positioning of Itata as a heritage wine destination in Chile.<\/p>\n<p>In this line, the national director of INDAP, C\u00e9sar Rodr\u00edguez, said that \"the producers who chose to dedicate themselves to the production of wines and distillates chose the most demanding path: that of quality, differentiation and deep commitment to their territory. From INDAP, we are fully committed to continue supporting and strengthening this effort, which today receives a well-deserved recognition in this important international competition such as Catad'Or\".<\/p>\n<h4>Relaying peasant family farming<\/h4>\n<p>The awards ceremony, held at the Monticello Gran Casino in San Francisco de Mostazal, also celebrated the 30th anniversary of this competition, considered the most important in Latin America and the only one in the region with the backing of the International Organisation of Vine and Wine (OIV) and VINOFED, the federation that brings together the world's leading wine competitions.<\/p>\n<p>At the national level, \u00d1uble's success is added to the recognition of producers from nine regions of the country, where 37 wineries, distilleries and family cider makers supported by INDAP received 53 medals: 2 Grand Gold, 43 Gold and 8 Silver.<\/p>\n<p>The achievements of Vi\u00f1a Melozal del Maule, which won the Trophy for Best Ancestral Distillate for its Brandy Pa\u00eds Dorado; Vi\u00f1a Los Oasis de Pica in Tarapac\u00e1, which received two gold medals; and the family businesses La Quinta Chilo\u00e9 and TerraLluvia Chilo\u00e9, from the Los Lagos Region, awarded for their ciders and spirits made with an agro-ecological seal and environmental commitment, stood out for example.<\/p>\n<p>Catad'Or 2025 thus reaffirms the potential of Chilean family farming and the quality of its products, demonstrating that work based on the land, identity and collaboration can compete on equal terms with the great names in the world of wine. More information at\u00a0<a target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.catador.cl\/premiados2025\">https:\/\/www.catador.cl\/premiados2025<\/a>.<\/p>\n<p>Did you see our previous content? <a href=\"https:\/\/dechilealpaladar.cl\/en\/un-tourism-adds-lolol-to-best-tourism-villages-programme\/\">UN Tourism adds Lolol to Best Tourism Villages programme<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La Agricultura Familiar Campesina del Valle del Itata volvi\u00f3 a ser protagonista en el escenario vitivin\u00edcola internacional. En la versi\u00f3n 2025 de los Catad\u2019Or World Wine Awards, el vino Do\u00f1a Elita Cinsault 2022, elaborado por la vi\u00f1a Do\u00f1a Elita de Elia Fierro en la comuna de R\u00e1nquil, obtuvo una Medalla Gran Oro y el Trofeo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3782,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"sidebar-single-post","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"1","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":"Vi\u00f1a Do\u00f1a Elita obtiene Gran Oro y otras 10 peque\u00f1os productores familiares lograron 14 medallas de oro"},"jnews_primary_category":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[6,29,11],"tags":[184,183,185,16,182],"class_list":["post-3779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-tendencias","category-vinos","tag-agricultura-familiar","tag-cataor-2025","tag-vinas-campesinas","tag-vinos","tag-vinos-ancestrales"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Agricultura Familiar Campesina del Valle del Itata volvi\u00f3 a ser protagonista en el escenario vitivin\u00edcola internacional. En la versi\u00f3n 2025 de los Catad\u2019Or World Wine Awards, el vino Do\u00f1a Elita Cinsault 2022, elaborado por la vi\u00f1a Do\u00f1a Elita de Elia Fierro en la comuna de R\u00e1nquil, obtuvo una Medalla Gran Oro y el Trofeo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Equipo De Chile Al Paladar\"\/>\n\t<meta name=\"google-site-verification\" content=\"FwbYXf8NSX7K5fFr17ZmyxG2GPBjQNe6D5Z26IIESJA\" \/>\n\t<meta name=\"p:domain_verify\" content=\"b1ea975e07205230074b4f8d7926d7df\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"De Chile al Paladar | Noticias del Vino en Chile - De Chile al Paladar celebra la cultura del vino, gastronom\u00eda y enoturismo, ofreciendo noticias, tendencias y rese\u00f1as con enfoque en el valor del patrimonio vitivin\u00edcola chileno y la sostenibilidad.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vi\u00f1as campesinas de \u00d1uble brillaron en Catad\u2019Or 2025\" \/>\n\t\t<meta property=\"og:description\" content=\"La Agricultura Familiar Campesina del Valle del Itata volvi\u00f3 a ser protagonista en el escenario vitivin\u00edcola internacional. En la versi\u00f3n 2025 de los Catad\u2019Or World Wine Awards, el vino Do\u00f1a Elita Cinsault 2022, elaborado por la vi\u00f1a Do\u00f1a Elita de Elia Fierro en la comuna de R\u00e1nquil, obtuvo una Medalla Gran Oro y el Trofeo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/entre-las-vinas-premiadas-figuran-trifulca-cortez-el-guindo-guarilihue-familiar-hermanos-diaz-la-kura-la-mision-de-francisco-san-luis-tres-c-y-viejo-encino.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/entre-las-vinas-premiadas-figuran-trifulca-cortez-el-guindo-guarilihue-familiar-hermanos-diaz-la-kura-la-mision-de-francisco-san-luis-tres-c-y-viejo-encino.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-11-07T21:03:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-07T23:27:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/dechilealpaladar\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Vi\u00f1as campesinas de \u00d1uble brillaron en Catad\u2019Or 2025\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Agricultura Familiar Campesina del Valle del Itata volvi\u00f3 a ser protagonista en el escenario vitivin\u00edcola internacional. En la versi\u00f3n 2025 de los Catad\u2019Or World Wine Awards, el vino Do\u00f1a Elita Cinsault 2022, elaborado por la vi\u00f1a Do\u00f1a Elita de Elia Fierro en la comuna de R\u00e1nquil, obtuvo una Medalla Gran Oro y el Trofeo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/entre-las-vinas-premiadas-figuran-trifulca-cortez-el-guindo-guarilihue-familiar-hermanos-diaz-la-kura-la-mision-de-francisco-san-luis-tres-c-y-viejo-encino.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#blogposting\",\"name\":\"Vi\\u00f1as campesinas de \\u00d1uble brillaron en Catad\\u2019Or 2025\",\"headline\":\"Vi\\u00f1as campesinas de \\u00d1uble brillaron en Catad&#8217;Or 2025\",\"author\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/author\\\/equipo-de-chile-al-paladar\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dechilealpaladar.cl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/entre-las-vinas-premiadas-figuran-trifulca-cortez-el-guindo-guarilihue-familiar-hermanos-diaz-la-kura-la-mision-de-francisco-san-luis-tres-c-y-viejo-encino.jpg\",\"width\":1160,\"height\":760},\"datePublished\":\"2025-11-07T18:03:15-03:00\",\"dateModified\":\"2025-11-07T20:27:16-03:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#webpage\"},\"articleSection\":\"Noticias, Tendencias, Vinos, Agricultura Familiar, Cata'Or 2025, Vi\\u00f1as Campesinas, Vinos, Vinos Ancestrales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/category\\\/vinos\\\/#listItem\",\"name\":\"Vinos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/category\\\/vinos\\\/#listItem\",\"position\":2,\"name\":\"Vinos\",\"item\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/category\\\/vinos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/category\\\/vinos\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/category\\\/vinos\\\/noticias\\\/#listItem\",\"position\":3,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/category\\\/vinos\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#listItem\",\"name\":\"Vi\\u00f1as campesinas de \\u00d1uble brillaron en Catad&#8217;Or 2025\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/category\\\/vinos\\\/#listItem\",\"name\":\"Vinos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#listItem\",\"position\":4,\"name\":\"Vi\\u00f1as campesinas de \\u00d1uble brillaron en Catad&#8217;Or 2025\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/category\\\/vinos\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/#organization\",\"name\":\"De Chile al Paladar\",\"description\":\"De Chile al Paladar es una plataforma dedicada a celebrar y promover la cultura del vino y la gastronom\\u00eda en Chile. Ofrecemos rese\\u00f1as de vinos, maridajes, tendencias, noticias y panoramas, destacando tanto los vinos tradicionales como los de peque\\u00f1os productores. Inspiramos a amantes del vino y la buena mesa a descubrir catas, ferias y las riquezas de la gastronom\\u00eda chilena.\",\"url\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/\",\"email\":\"equipo@dechilealpaladar.cl\",\"telephone\":\"+56976152439\",\"foundingDate\":\"2025-03-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":0,\"maxValue\":10},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dechilealpaladar.cl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/De_Chile_al_Paladar_Logo_Color-1.png\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#organizationLogo\",\"width\":310,\"height\":200,\"caption\":\"DeChileAlPaladar\"},\"image\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/dechilealpaladar\",\"https:\\\/\\\/instagram.com\\\/dechilealpaladar\",\"https:\\\/\\\/youtube.com\\\/dechilealpaladar\",\"https:\\\/\\\/linkedin.com\\\/in\\\/dechilealpaladar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/author\\\/equipo-de-chile-al-paladar\\\/#author\",\"url\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/author\\\/equipo-de-chile-al-paladar\\\/\",\"name\":\"Equipo De Chile Al Paladar\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dechilealpaladar.cl\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo_equipo_dcap.png\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#webpage\",\"url\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/\",\"name\":\"Vi\\u00f1as campesinas de \\u00d1uble brillaron en Catad\\u2019Or 2025\",\"description\":\"La Agricultura Familiar Campesina del Valle del Itata volvi\\u00f3 a ser protagonista en el escenario vitivin\\u00edcola internacional. En la versi\\u00f3n 2025 de los Catad\\u2019Or World Wine Awards, el vino Do\\u00f1a Elita Cinsault 2022, elaborado por la vi\\u00f1a Do\\u00f1a Elita de Elia Fierro en la comuna de R\\u00e1nquil, obtuvo una Medalla Gran Oro y el Trofeo\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/author\\\/equipo-de-chile-al-paladar\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/author\\\/equipo-de-chile-al-paladar\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dechilealpaladar.cl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/entre-las-vinas-premiadas-figuran-trifulca-cortez-el-guindo-guarilihue-familiar-hermanos-diaz-la-kura-la-mision-de-francisco-san-luis-tres-c-y-viejo-encino.jpg\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#mainImage\",\"width\":1160,\"height\":760},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\\\/#mainImage\"},\"datePublished\":\"2025-11-07T18:03:15-03:00\",\"dateModified\":\"2025-11-07T20:27:16-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/\",\"name\":\"De Chile al Paladar | Noticias del Vino en Chile\",\"alternateName\":\"De Chile al Paladar\",\"description\":\"De Chile al Paladar celebra la cultura del vino, gastronom\\u00eda y enoturismo, ofreciendo noticias, tendencias y rese\\u00f1as con enfoque en el valor del patrimonio vitivin\\u00edcola chileno y la sostenibilidad.\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/dechilealpaladar.cl\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Vi\u00f1as campesinas de \u00d1uble brillaron en Catad\u2019Or 2025<\/title>\n\n","aioseo_head_json":{"title":"\u00d1uble's small-scale vineyards shone at Catad'Or 2025","description":"The Itata Valley's peasant family agriculture once again took centre stage on the international wine scene. In the 2025 version of the Catad'Or World Wine Awards, the wine Do\u00f1a Elita Cinsault 2022, produced by Elia Fierro's Do\u00f1a Elita winery in the commune of R\u00e1nquil, was awarded a Grand Gold Medal and the","canonical_url":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"FwbYXf8NSX7K5fFr17ZmyxG2GPBjQNe6D5Z26IIESJA","p:domain_verify":"b1ea975e07205230074b4f8d7926d7df","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#blogposting","name":"Vi\u00f1as campesinas de \u00d1uble brillaron en Catad\u2019Or 2025","headline":"Vi\u00f1as campesinas de \u00d1uble brillaron en Catad&#8217;Or 2025","author":{"@id":"https:\/\/dechilealpaladar.cl\/en\/author\/equipo-de-chile-al-paladar\/#author"},"publisher":{"@id":"https:\/\/dechilealpaladar.cl\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/entre-las-vinas-premiadas-figuran-trifulca-cortez-el-guindo-guarilihue-familiar-hermanos-diaz-la-kura-la-mision-de-francisco-san-luis-tres-c-y-viejo-encino.jpg","width":1160,"height":760},"datePublished":"2025-11-07T18:03:15-03:00","dateModified":"2025-11-07T20:27:16-03:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#webpage"},"isPartOf":{"@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#webpage"},"articleSection":"Noticias, Tendencias, Vinos, Agricultura Familiar, Cata'Or 2025, Vi\u00f1as Campesinas, Vinos, Vinos Ancestrales"},{"@type":"BreadcrumbList","@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dechilealpaladar.cl\/en#listItem","position":1,"name":"Home","item":"https:\/\/dechilealpaladar.cl\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/#listItem","name":"Vinos"}},{"@type":"ListItem","@id":"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/#listItem","position":2,"name":"Vinos","item":"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/noticias\/#listItem","name":"Noticias"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dechilealpaladar.cl\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/noticias\/#listItem","position":3,"name":"Noticias","item":"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#listItem","name":"Vi\u00f1as campesinas de \u00d1uble brillaron en Catad&#8217;Or 2025"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/#listItem","name":"Vinos"}},{"@type":"ListItem","@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#listItem","position":4,"name":"Vi\u00f1as campesinas de \u00d1uble brillaron en Catad&#8217;Or 2025","previousItem":{"@type":"ListItem","@id":"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/dechilealpaladar.cl\/en\/#organization","name":"De Chile al Paladar","description":"De Chile al Paladar es una plataforma dedicada a celebrar y promover la cultura del vino y la gastronom\u00eda en Chile. Ofrecemos rese\u00f1as de vinos, maridajes, tendencias, noticias y panoramas, destacando tanto los vinos tradicionales como los de peque\u00f1os productores. Inspiramos a amantes del vino y la buena mesa a descubrir catas, ferias y las riquezas de la gastronom\u00eda chilena.","url":"https:\/\/dechilealpaladar.cl\/en\/","email":"equipo@dechilealpaladar.cl","telephone":"+56976152439","foundingDate":"2025-03-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":0,"maxValue":10},"logo":{"@type":"ImageObject","url":"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2024\/11\/De_Chile_al_Paladar_Logo_Color-1.png","@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#organizationLogo","width":310,"height":200,"caption":"DeChileAlPaladar"},"image":{"@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/dechilealpaladar","https:\/\/instagram.com\/dechilealpaladar","https:\/\/youtube.com\/dechilealpaladar","https:\/\/linkedin.com\/in\/dechilealpaladar"]},{"@type":"Person","@id":"https:\/\/dechilealpaladar.cl\/en\/author\/equipo-de-chile-al-paladar\/#author","url":"https:\/\/dechilealpaladar.cl\/en\/author\/equipo-de-chile-al-paladar\/","name":"Equipo De Chile Al Paladar","image":{"@type":"ImageObject","url":"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/08\/logo_equipo_dcap.png"}},{"@type":"WebPage","@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#webpage","url":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/","name":"Vi\u00f1as campesinas de \u00d1uble brillaron en Catad\u2019Or 2025","description":"La Agricultura Familiar Campesina del Valle del Itata volvi\u00f3 a ser protagonista en el escenario vitivin\u00edcola internacional. En la versi\u00f3n 2025 de los Catad\u2019Or World Wine Awards, el vino Do\u00f1a Elita Cinsault 2022, elaborado por la vi\u00f1a Do\u00f1a Elita de Elia Fierro en la comuna de R\u00e1nquil, obtuvo una Medalla Gran Oro y el Trofeo","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/dechilealpaladar.cl\/en\/#website"},"breadcrumb":{"@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#breadcrumblist"},"author":{"@id":"https:\/\/dechilealpaladar.cl\/en\/author\/equipo-de-chile-al-paladar\/#author"},"creator":{"@id":"https:\/\/dechilealpaladar.cl\/en\/author\/equipo-de-chile-al-paladar\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/entre-las-vinas-premiadas-figuran-trifulca-cortez-el-guindo-guarilihue-familiar-hermanos-diaz-la-kura-la-mision-de-francisco-san-luis-tres-c-y-viejo-encino.jpg","@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#mainImage","width":1160,"height":760},"primaryImageOfPage":{"@id":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/#mainImage"},"datePublished":"2025-11-07T18:03:15-03:00","dateModified":"2025-11-07T20:27:16-03:00"},{"@type":"WebSite","@id":"https:\/\/dechilealpaladar.cl\/en\/#website","url":"https:\/\/dechilealpaladar.cl\/en\/","name":"De Chile al Paladar | Noticias del Vino en Chile","alternateName":"De Chile al Paladar","description":"De Chile al Paladar celebra la cultura del vino, gastronom\u00eda y enoturismo, ofreciendo noticias, tendencias y rese\u00f1as con enfoque en el valor del patrimonio vitivin\u00edcola chileno y la sostenibilidad.","inLanguage":"en-GB","publisher":{"@id":"https:\/\/dechilealpaladar.cl\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"De Chile al Paladar | Noticias del Vino en Chile - De Chile al Paladar celebra la cultura del vino, gastronom\u00eda y enoturismo, ofreciendo noticias, tendencias y rese\u00f1as con enfoque en el valor del patrimonio vitivin\u00edcola chileno y la sostenibilidad.","og:type":"article","og:title":"Vi\u00f1as campesinas de \u00d1uble brillaron en Catad\u2019Or 2025","og:description":"La Agricultura Familiar Campesina del Valle del Itata volvi\u00f3 a ser protagonista en el escenario vitivin\u00edcola internacional. En la versi\u00f3n 2025 de los Catad\u2019Or World Wine Awards, el vino Do\u00f1a Elita Cinsault 2022, elaborado por la vi\u00f1a Do\u00f1a Elita de Elia Fierro en la comuna de R\u00e1nquil, obtuvo una Medalla Gran Oro y el Trofeo","og:url":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/","og:image":"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/entre-las-vinas-premiadas-figuran-trifulca-cortez-el-guindo-guarilihue-familiar-hermanos-diaz-la-kura-la-mision-de-francisco-san-luis-tres-c-y-viejo-encino.jpg","og:image:secure_url":"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/entre-las-vinas-premiadas-figuran-trifulca-cortez-el-guindo-guarilihue-familiar-hermanos-diaz-la-kura-la-mision-de-francisco-san-luis-tres-c-y-viejo-encino.jpg","og:image:width":1160,"og:image:height":760,"article:published_time":"2025-11-07T21:03:15+00:00","article:modified_time":"2025-11-07T23:27:16+00:00","article:publisher":"https:\/\/facebook.com\/dechilealpaladar","twitter:card":"summary_large_image","twitter:title":"Vi\u00f1as campesinas de \u00d1uble brillaron en Catad\u2019Or 2025","twitter:description":"La Agricultura Familiar Campesina del Valle del Itata volvi\u00f3 a ser protagonista en el escenario vitivin\u00edcola internacional. En la versi\u00f3n 2025 de los Catad\u2019Or World Wine Awards, el vino Do\u00f1a Elita Cinsault 2022, elaborado por la vi\u00f1a Do\u00f1a Elita de Elia Fierro en la comuna de R\u00e1nquil, obtuvo una Medalla Gran Oro y el Trofeo","twitter:image":"https:\/\/dechilealpaladar.cl\/wp-content\/uploads\/2025\/11\/entre-las-vinas-premiadas-figuran-trifulca-cortez-el-guindo-guarilihue-familiar-hermanos-diaz-la-kura-la-mision-de-francisco-san-luis-tres-c-y-viejo-encino.jpg"},"aioseo_meta_data":{"post_id":"3779","title":"#post_title","description":"#post_excerpt","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-11-07 23:27:39","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-11-07 20:34:56","updated":"2025-11-07 23:46:48"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/dechilealpaladar.cl\/en\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/\" title=\"Vinos\">Vinos<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tVi\u00f1as campesinas de \u00d1uble brillaron en Catad\u2019Or 2025\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/dechilealpaladar.cl\/en"},{"label":"Vinos","link":"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/"},{"label":"Noticias","link":"https:\/\/dechilealpaladar.cl\/en\/category\/vinos\/noticias\/"},{"label":"Vi\u00f1as campesinas de \u00d1uble brillaron en Catad&#8217;Or 2025","link":"https:\/\/dechilealpaladar.cl\/en\/vinas-campesinas-de-nuble-brillaron-en-catador-2025\/"}],"_links":{"self":[{"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/posts\/3779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/comments?post=3779"}],"version-history":[{"count":1,"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/posts\/3779\/revisions"}],"predecessor-version":[{"id":3784,"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/posts\/3779\/revisions\/3784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/media\/3782"}],"wp:attachment":[{"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/media?parent=3779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/categories?post=3779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dechilealpaladar.cl\/en\/wp-json\/wp\/v2\/tags?post=3779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}